{"id":266,"date":"2013-12-06T14:28:29","date_gmt":"2013-12-06T13:28:29","guid":{"rendered":"http:\/\/www.mjlesgaislurons.be\/wordpress\/?p=266"},"modified":"2015-11-26T14:59:47","modified_gmt":"2015-11-26T13:59:47","slug":"marche-de-noel-2014","status":"publish","type":"post","link":"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/","title":{"rendered":"March\u00e9 de No\u00ebl 2014"},"content":{"rendered":"<p><a href=\"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/12\/Affiche-march\u00e9-de-noel-MJ-2014.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-272\" src=\"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/12\/Affiche-march\u00e9-de-noel-MJ-2014.jpg\" alt=\"Affiche march\u00e9 de noel MJ 2014\" width=\"720\" height=\"960\" srcset=\"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/12\/Affiche-march\u00e9-de-noel-MJ-2014.jpg 720w, https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/12\/Affiche-march\u00e9-de-noel-MJ-2014-225x300.jpg 225w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":263,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-266","post","type-post","status-publish","format-standard","hentry","category-evenement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>March\u00e9 de No\u00ebl 2014 - Maison des Jeunes Les Gais Lurons Asbl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"March\u00e9 de No\u00ebl 2014 - Maison des Jeunes Les Gais Lurons Asbl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/\" \/>\n<meta property=\"og:site_name\" content=\"Maison des Jeunes Les Gais Lurons Asbl\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-06T13:28:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-26T13:59:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/06\/217342_533947193307580_1985264166_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/\",\"url\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/\",\"name\":\"March\u00e9 de No\u00ebl 2014 - Maison des Jeunes Les Gais Lurons Asbl\",\"isPartOf\":{\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/06\/217342_533947193307580_1985264166_n.jpg\",\"datePublished\":\"2013-12-06T13:28:29+00:00\",\"dateModified\":\"2015-11-26T13:59:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/#\/schema\/person\/837d59ad8ea87f0b341813859ff7fe61\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/#primaryimage\",\"url\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/06\/217342_533947193307580_1985264166_n.jpg\",\"contentUrl\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/06\/217342_533947193307580_1985264166_n.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9V\u00c9NEMENT\",\"item\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/category\/evenement\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"March\u00e9 de No\u00ebl 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/#website\",\"url\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/\",\"name\":\"Maison des Jeunes Les Gais Lurons Asbl\",\"description\":\"Nous sommes la pour vous!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/#\/schema\/person\/837d59ad8ea87f0b341813859ff7fe61\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e2b6c991fcafc7d501bb9eab318623daf78b5d559f4256f9aa307b17a09364c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e2b6c991fcafc7d501bb9eab318623daf78b5d559f4256f9aa307b17a09364c7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"Animateur b\u00e9n\u00e9vole Espace Public Num\u00e9rique et administrateur de la Maison des Jeunes les Gais Lurons de Gosselies ASBL. Exp\u00e9rience de 28 ann\u00e9es dans l'informatique (Siemens Nixdorf, Orange BE et TechMahindra).\",\"url\":\"https:\/\/www.mjlesgaislurons.be\/wordpress\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"March\u00e9 de No\u00ebl 2014 - Maison des Jeunes Les Gais Lurons Asbl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/","og_locale":"fr_FR","og_type":"article","og_title":"March\u00e9 de No\u00ebl 2014 - Maison des Jeunes Les Gais Lurons Asbl","og_url":"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/","og_site_name":"Maison des Jeunes Les Gais Lurons Asbl","article_published_time":"2013-12-06T13:28:29+00:00","article_modified_time":"2015-11-26T13:59:47+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/06\/217342_533947193307580_1985264166_n.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/","url":"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/","name":"March\u00e9 de No\u00ebl 2014 - Maison des Jeunes Les Gais Lurons Asbl","isPartOf":{"@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/#primaryimage"},"image":{"@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/06\/217342_533947193307580_1985264166_n.jpg","datePublished":"2013-12-06T13:28:29+00:00","dateModified":"2015-11-26T13:59:47+00:00","author":{"@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/#\/schema\/person\/837d59ad8ea87f0b341813859ff7fe61"},"breadcrumb":{"@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/#primaryimage","url":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/06\/217342_533947193307580_1985264166_n.jpg","contentUrl":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-content\/uploads\/2013\/06\/217342_533947193307580_1985264166_n.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/marche-de-noel-2014\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mjlesgaislurons.be\/wordpress\/"},{"@type":"ListItem","position":2,"name":"\u00c9V\u00c9NEMENT","item":"https:\/\/www.mjlesgaislurons.be\/wordpress\/category\/evenement\/"},{"@type":"ListItem","position":3,"name":"March\u00e9 de No\u00ebl 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/#website","url":"https:\/\/www.mjlesgaislurons.be\/wordpress\/","name":"Maison des Jeunes Les Gais Lurons Asbl","description":"Nous sommes la pour vous!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mjlesgaislurons.be\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/#\/schema\/person\/837d59ad8ea87f0b341813859ff7fe61","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mjlesgaislurons.be\/wordpress\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e2b6c991fcafc7d501bb9eab318623daf78b5d559f4256f9aa307b17a09364c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e2b6c991fcafc7d501bb9eab318623daf78b5d559f4256f9aa307b17a09364c7?s=96&d=mm&r=g","caption":"admin"},"description":"Animateur b\u00e9n\u00e9vole Espace Public Num\u00e9rique et administrateur de la Maison des Jeunes les Gais Lurons de Gosselies ASBL. Exp\u00e9rience de 28 ann\u00e9es dans l'informatique (Siemens Nixdorf, Orange BE et TechMahindra).","url":"https:\/\/www.mjlesgaislurons.be\/wordpress\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/posts\/266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/comments?post=266"}],"version-history":[{"count":5,"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/posts\/266\/revisions"}],"predecessor-version":[{"id":294,"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/posts\/266\/revisions\/294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/media\/263"}],"wp:attachment":[{"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/media?parent=266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/categories?post=266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mjlesgaislurons.be\/wordpress\/wp-json\/wp\/v2\/tags?post=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}